{"id":3156,"date":"2013-12-02T18:45:19","date_gmt":"2013-12-02T18:45:19","guid":{"rendered":"http:\/\/www.phil.ca\/collectes-par-des-tiers-partis-un-phare-despoir\/"},"modified":"2019-10-31T20:39:07","modified_gmt":"2019-10-31T20:39:07","slug":"collectes-par-des-tiers-partis-un-phare-despoir","status":"publish","type":"post","link":"https:\/\/phil.ca\/fr\/collectes-par-des-tiers-partis-un-phare-despoir\/","title":{"rendered":"Collectes par des tiers partis: un Phare d\u2019espoir"},"content":{"rendered":"<h4 dir=\"ltr\">Le Phare Enfants et Familles<\/h4>\n<p dir=\"ltr\">Depuis 1999, <a href=\"http:\/\/www.phare-lighthouse.com\/\">Le Phare Enfants et Familles<\/a>, organisme sans but lucratif, contribue au bien-\u00eatre des enfants atteints de maladies n\u00e9cessitant des soins complexes et apporte r\u00e9pit et soutien \u00e0 leurs familles. Le Phare accueille ces enfants \u00e0 la Maison Andr\u00e9-Gratton, seule maison de soins palliatifs p\u00e9diatriques au Qu\u00e9bec, offrant \u00e0 la fois s\u00e9jours de r\u00e9pit et soins de fin de vie. L\u2019organisme offre aussi du r\u00e9pit \u00e0 domicile et accompagne les familles.<\/p>\n<p dir=\"ltr\">Accompagner les jeunes atteints d\u2019une maladie grave ou leur offrir des soins de fin de vie, c\u2019est une cause noble qui interpelle un grand nombre de gens. Si bien, en fait, qu\u2019au fil des ans, Le Phare a commenc\u00e9 \u00e0 recevoir de plus en plus de demandes de tierces parties pour collecter des fonds en son nom. L\u2019organisme \u00e9tait aux prises avec un probl\u00e8me heureux, mais fortement inhabituel: trop de donateurs sans encadrement puisaient dans les ressources du Phare pour mener leurs campagnes \u00e0 bien.<\/p>\n<p dir=\"ltr\">C\u2019est Phil Communications qui a \u00e9t\u00e9 mandat\u00e9 de solutionner ce probl\u00e8me: r\u00e9duire les t\u00e2ches administratives, augmenter la participation et la notori\u00e9t\u00e9 de la marque, et impliquer plus de gens pour pouvoir amasser plus de fonds.<\/p>\n<h4 dir=\"ltr\">Tout probl\u00e8me unique requiert une solution originale&#8230;<\/h4>\n<p dir=\"ltr\">La collaboration entre Le Phare et Phil Communications a d\u00e9but\u00e9 il y a plus de cinq ans avec une vari\u00e9t\u00e9 de besoins en marketing et communications \u00e0 plus petite \u00e9chelle. Manon Durocher, Directrice du d\u00e9veloppement financier et des communications chez Le Phare, admet d\u2019embl\u00e9e que l\u2019organisme avait peu d\u2019expertise en communications avant de recourir aux services de Phil. La gestion des collectes de fonds externes \u00e9tait faite sur une base b\u00e9n\u00e9vole. Il fallait donc cr\u00e9er et mettre en place un bon plan de communications (pr\u00e9par\u00e9 par les experts de Phil) qui serait g\u00e9r\u00e9 par un poste permanent au sein de la fondation. Le plan d\u00e9taillait les objectifs strat\u00e9giques du programme, les publics \u00e0 cibler, les tribunes \u00e0 utiliser et un plan de mise en place sur 12 mois.<\/p>\n<p dir=\"ltr\">Le besoin de remaniement du personnel en communications \u00e9tait bien compris par Mme. Durocher. Elle avait toutefois des r\u00e9serves quand \u00e0 l\u2019application trop rapide d\u2019un programme qui allait changer la structure, le budget et le fonctionnement du Phare. C\u2019est pourquoi Phil a \u00e9tendu la phase de d\u00e9veloppement du plan <a href=\"https:\/\/www.unispourlephare.com\/\">\u00ab UNIS pour Le Phare \u00bb<\/a> sur deux ans.<\/p>\n<h4 dir=\"ltr\">UNIS pour Le Phare<\/h4>\n<p dir=\"ltr\"><a href=\"https:\/\/www.phil.ca\/wp-content\/uploads\/2013\/11\/cs_PEF_EtoileUnis.png\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-1635\" src=\"https:\/\/www.phil.ca\/wp-content\/uploads\/2013\/11\/cs_PEF_EtoileUnis.png\" alt=\"cs_PEF_EtoileUnis\" width=\"300\" height=\"283\" \/><\/a><\/p>\n<p dir=\"ltr\">Le programme UNIS a pour objectif de permettre \u00e0 des tierces parties de contribuer au Phare en organisant eux-m\u00eames des collectes de fonds \u00e0 l\u2019aide de mat\u00e9riels fournis par l\u2019organisme. Dans la trousse \u00ab UNIS pour Le Phare \u00bb, on trouve entre autres des formulaires de dons, des grilles de collectes de fonds et un mod\u00e8le de lettre de solicitation. L\u2019outil le plus important, toutefois, est sans \u00e9quivoque l\u2019\u00e9toile du programme UNIS.<\/p>\n<p dir=\"ltr\">Le concept est simple et abordable: on parle d\u2019une \u00e9toile jaune avec bordure mauve en carton d\u00e9coup\u00e9 dans la m\u00eame forme que l\u2019\u00e9toile du logo du Phare. Les participants de toutes les collectes de fonds sont invit\u00e9s \u00e0 inscrire leur nom ou le nom d\u2019un enfant malade sur une \u00e9toile et \u00e0 se faire photographier en la tenant. Cet outil ne sert pas seulement \u00e0 motiver les participants; faciles \u00e0 partager, les photographies r\u00e9sultantes sont un outil de r\u00e9f\u00e9rencement indispensable sur les m\u00e9dias sociaux. Cet aspect fut un franc succ\u00e8s, et d\u00e8s la premi\u00e8re ann\u00e9e du programme UNIS, on a vu une multitude de photos partag\u00e9es sur les <a href=\"https:\/\/www.facebook.com\/PhareEnfantsFamilles\">r\u00e9seaux sociaux<\/a>. Les gens ont vraiment embarqu\u00e9, tant dans l\u2019aspect cr\u00e9atif que social du projet.<\/p>\n<p><em id=\"__mceDel\"><a href=\"https:\/\/www.phil.ca\/wp-content\/uploads\/2013\/11\/cs_PEF_stars.jpg\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-1636\" src=\"https:\/\/www.phil.ca\/wp-content\/uploads\/2013\/11\/cs_PEF_stars.jpg\" alt=\"cs_PEF_stars\" width=\"760\" height=\"158\" \/><\/a><\/em><\/p>\n<p>&nbsp;<\/p>\n<h4 dir=\"ltr\">Collaboration; ex\u00e9cution; r\u00e9sultats<\/h4>\n<p dir=\"ltr\">La belle relation de confiance b\u00e2tie entre Phil et Le Phare a permis la r\u00e9ussite du programme. L\u2019ouverture d\u2019esprit et la rigueur au travail du Phare a permis \u00e0 Phil de pr\u00e9senter ses id\u00e9es, dont le concept de l\u2019\u00e9toile UNIS et les microsites qui l\u2019accompagnent, ainsi que l\u2019aspect de partage sur les r\u00e9seaux sociaux, qui a eu un impact sup\u00e9rieur encore aux \u00e9v\u00e9nements eux-m\u00eames! La patience de Phil envers le rhythme de mise en place du programme impos\u00e9 par Le Phare a port\u00e9 ses fruits et le processus de mise en place s\u2019est fait en douceur.<\/p>\n<p dir=\"ltr\">Le Phare a maintenant un poste permanent d\u00e9di\u00e9 \u00e0 la gestion du programme UNIS. Ce remaniement administratif a grandement simplifi\u00e9 la t\u00e2che du Phare tout en augmentant de fa\u00e7on significative sa visibilit\u00e9. Par le fait m\u00eame, \u00e7a a permis aux initiatives ind\u00e9pendantes de se multiplier.<\/p>\n<p dir=\"ltr\">Dans la premi\u00e8re ann\u00e9e du programme, le nombre d\u2019initiatives entreprises par des tiers-partis a doubl\u00e9, passant d\u2019une trentaine de projets \u00e0 une soixantaine! L\u2019objectif de cette ann\u00e9e est de doubler encore la participation pour faire rayonner Le Phare dans 120 \u00e9v\u00e9nements, ce qui semble bien en vue de se r\u00e9aliser. D\u00e9j\u00e0, 27 entreprises, 19 groupes communautaires et 15 citoyens individuels ont cr\u00e9\u00e9 des initiatives amassant des montants variant de quelques centaines \u00e0 des dizaines de milliers de dollars!<\/p>\n<div dir=\"ltr\">\n<table>\n<colgroup>\n<col width=\"145\" \/>\n<col width=\"180\" \/>\n<col width=\"210\" \/><\/colgroup>\n<tbody>\n<tr>\n<td>\n<p dir=\"ltr\">Mise en place<\/p>\n<\/td>\n<td>\n<p dir=\"ltr\">D\u00e9but du plan UNIS<\/p>\n<\/td>\n<td>\n<p dir=\"ltr\">Deuxi\u00e8me ann\u00e9e<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p dir=\"ltr\">2010-2011<\/p>\n<\/td>\n<td>\n<p dir=\"ltr\">2011-2012<\/p>\n<\/td>\n<td>\n<p dir=\"ltr\">2012-2013<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td>\n<p dir=\"ltr\">33,527.00 \u00a0$<\/p>\n<\/td>\n<td>\n<p dir=\"ltr\">55,318.00 \u00a0$<\/p>\n<\/td>\n<td>\n<p dir=\"ltr\">156,511.00 \u00a0$<\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p dir=\"ltr\">Outre la simplification administrative, Le Phare a grandement b\u00e9n\u00e9fici\u00e9 de la popularit\u00e9 de <a href=\"https:\/\/www.unispourlephare.com\/\">\u00ab UNIS pour Le Phare \u00bb<\/a> sur les r\u00e9seaux sociaux; \u00e7a a augment\u00e9 l\u2019achalandage des microsites et la visibilit\u00e9 du Phare en ligne. Surtout, la plus grande satisfaction nous vient lorsqu\u2019on voit les sourires des enfants malades qui ont pu b\u00e9n\u00e9ficier des services du Phare avec notre aide.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Phare Enfants et Familles Depuis 1999, Le Phare Enfants et Familles, organisme sans but lucratif, contribue au bien-\u00eatre des enfants atteints de maladies n\u00e9cessitant des soins complexes et apporte r\u00e9pit et soutien \u00e0 leurs familles. Le Phare accueille ces enfants \u00e0 la Maison Andr\u00e9-Gratton, seule maison de soins palliatifs p\u00e9diatriques au Qu\u00e9bec, offrant \u00e0 la fois s\u00e9jours de r\u00e9pit et soins de fin de vie. L\u2019organisme offre aussi du r\u00e9pit \u00e0 domicile et accompagne les familles. Accompagner les jeunes atteints d\u2019une maladie grave ou leur offrir des soins de fin de vie, c\u2019est une cause noble qui interpelle un grand nombre de gens. Si bien, en fait, qu\u2019au fil des ans, Le Phare a commenc\u00e9 \u00e0 recevoir de plus en plus de demandes de tierces parties pour collecter des fonds en son nom. L\u2019organisme \u00e9tait aux prises avec un probl\u00e8me heureux, mais fortement inhabituel: trop de donateurs sans encadrement puisaient dans les ressources du Phare pour mener leurs campagnes \u00e0 bien. C\u2019est Phil Communications qui a \u00e9t\u00e9 mandat\u00e9 de solutionner ce probl\u00e8me: r\u00e9duire les t\u00e2ches administratives, augmenter la participation et la notori\u00e9t\u00e9 de la marque, et impliquer plus de gens pour pouvoir amasser plus de fonds. Tout probl\u00e8me unique requiert une solution originale&#8230; La collaboration entre Le Phare et Phil Communications a d\u00e9but\u00e9 il y a plus de cinq ans avec une vari\u00e9t\u00e9 de besoins en marketing et communications \u00e0 plus petite \u00e9chelle. Manon Durocher, Directrice du d\u00e9veloppement financier et des communications chez Le Phare, admet d\u2019embl\u00e9e que l\u2019organisme avait peu d\u2019expertise en communications avant de recourir aux services de Phil. La gestion des collectes de fonds externes \u00e9tait faite sur une base b\u00e9n\u00e9vole. Il fallait donc cr\u00e9er et mettre en place un bon plan de communications (pr\u00e9par\u00e9 par les experts de Phil) qui serait g\u00e9r\u00e9 par un poste permanent au sein de la fondation. Le plan d\u00e9taillait les objectifs strat\u00e9giques du programme, les publics \u00e0 cibler, les tribunes \u00e0 utiliser et un plan de mise en place sur 12 mois. Le besoin de remaniement du personnel en communications \u00e9tait bien compris par Mme. Durocher. Elle avait toutefois des r\u00e9serves quand \u00e0 l\u2019application trop rapide d\u2019un programme qui allait changer la structure, le budget et le fonctionnement du Phare. C\u2019est pourquoi Phil a \u00e9tendu la phase de d\u00e9veloppement du plan \u00ab UNIS pour Le Phare \u00bb sur deux ans. UNIS pour Le Phare Le programme UNIS a pour objectif de permettre \u00e0 des tierces parties de contribuer au Phare en organisant eux-m\u00eames des collectes de fonds \u00e0 l\u2019aide de mat\u00e9riels fournis par l\u2019organisme. Dans la trousse \u00ab UNIS pour Le Phare \u00bb, on trouve entre autres des formulaires de dons, des grilles de collectes de fonds et un mod\u00e8le de lettre de solicitation. L\u2019outil le plus important, toutefois, est sans \u00e9quivoque l\u2019\u00e9toile du programme UNIS. Le concept est simple et abordable: on parle d\u2019une \u00e9toile jaune avec bordure mauve en carton d\u00e9coup\u00e9 dans la m\u00eame forme que l\u2019\u00e9toile du logo du Phare. Les participants de toutes les collectes de fonds sont invit\u00e9s \u00e0 inscrire leur nom ou le nom d\u2019un enfant malade sur une \u00e9toile et \u00e0 se faire photographier en la tenant. Cet outil ne sert pas seulement \u00e0 motiver les participants; faciles \u00e0 partager, les photographies r\u00e9sultantes sont un outil de r\u00e9f\u00e9rencement indispensable sur les m\u00e9dias sociaux. Cet aspect fut un franc succ\u00e8s, et d\u00e8s la premi\u00e8re ann\u00e9e du programme UNIS, on a vu une multitude de photos partag\u00e9es sur les r\u00e9seaux sociaux. Les gens ont vraiment embarqu\u00e9, tant dans l\u2019aspect cr\u00e9atif que social du projet. &nbsp; Collaboration; ex\u00e9cution; r\u00e9sultats La belle relation de confiance b\u00e2tie entre Phil et Le Phare a permis la r\u00e9ussite du programme. L\u2019ouverture d\u2019esprit et la rigueur au travail du Phare a permis \u00e0 Phil de pr\u00e9senter ses id\u00e9es, dont le concept de l\u2019\u00e9toile UNIS et les microsites qui l\u2019accompagnent, ainsi que l\u2019aspect de partage sur les r\u00e9seaux sociaux, qui a eu un impact sup\u00e9rieur encore aux \u00e9v\u00e9nements eux-m\u00eames! La patience de Phil envers le rhythme de mise en place du programme impos\u00e9 par Le Phare a port\u00e9 ses fruits et le processus de mise en place s\u2019est fait en douceur. Le Phare a maintenant un poste permanent d\u00e9di\u00e9 \u00e0 la gestion du programme UNIS. Ce remaniement administratif a grandement simplifi\u00e9 la t\u00e2che du Phare tout en augmentant de fa\u00e7on significative sa visibilit\u00e9. Par le fait m\u00eame, \u00e7a a permis aux initiatives ind\u00e9pendantes de se multiplier. Dans la premi\u00e8re ann\u00e9e du programme, le nombre d\u2019initiatives entreprises par des tiers-partis a doubl\u00e9, passant d\u2019une trentaine de projets \u00e0 une soixantaine! L\u2019objectif de cette ann\u00e9e est de doubler encore la participation pour faire rayonner Le Phare dans 120 \u00e9v\u00e9nements, ce qui semble bien en vue de se r\u00e9aliser. D\u00e9j\u00e0, 27 entreprises, 19 groupes communautaires et 15 citoyens individuels ont cr\u00e9\u00e9 des initiatives amassant des montants variant de quelques centaines \u00e0 des dizaines de milliers de dollars! Mise en place D\u00e9but du plan UNIS Deuxi\u00e8me ann\u00e9e 2010-2011 2011-2012 2012-2013 33,527.00 \u00a0$ 55,318.00 \u00a0$ 156,511.00 \u00a0$ Outre la simplification administrative, Le Phare a grandement b\u00e9n\u00e9fici\u00e9 de la popularit\u00e9 de \u00ab UNIS pour Le Phare \u00bb sur les r\u00e9seaux sociaux; \u00e7a a augment\u00e9 l\u2019achalandage des microsites et la visibilit\u00e9 du Phare en ligne. Surtout, la plus grande satisfaction nous vient lorsqu\u2019on voit les sourires des enfants malades qui ont pu b\u00e9n\u00e9ficier des services du Phare avec notre aide.<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[32],"tags":[],"class_list":["post-3156","post","type-post","status-publish","format-standard","hentry","category-articles-fr"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/phil.ca\/fr\/wp-json\/wp\/v2\/posts\/3156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/phil.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/phil.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/phil.ca\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/phil.ca\/fr\/wp-json\/wp\/v2\/comments?post=3156"}],"version-history":[{"count":1,"href":"https:\/\/phil.ca\/fr\/wp-json\/wp\/v2\/posts\/3156\/revisions"}],"predecessor-version":[{"id":50476,"href":"https:\/\/phil.ca\/fr\/wp-json\/wp\/v2\/posts\/3156\/revisions\/50476"}],"wp:attachment":[{"href":"https:\/\/phil.ca\/fr\/wp-json\/wp\/v2\/media?parent=3156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/phil.ca\/fr\/wp-json\/wp\/v2\/categories?post=3156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/phil.ca\/fr\/wp-json\/wp\/v2\/tags?post=3156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}